{"id":13172,"date":"2022-08-03T00:00:00","date_gmt":"2022-08-02T22:00:00","guid":{"rendered":"https:\/\/tresipunt.com\/3ipunt-primer-premium-partner-de-moodle-de-espana\/"},"modified":"2024-01-27T19:53:41","modified_gmt":"2024-01-27T18:53:41","slug":"3ipunt-primer-premium-partner-de-moodle-de-espana","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/3ipunt-primer-premium-partner-de-moodle-de-espana\/","title":{"rendered":"3ipunt, primer Premium Partner de Moodle de Espa\u00f1a"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/3ipunt-primer-premium-partner-de-moodle-de-espana\/#%C2%BFQue_es_ser_Premium_Partner_de_Moodle\" >\u00bfQu\u00e9 es ser Premium Partner de Moodle?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/3ipunt-primer-premium-partner-de-moodle-de-espana\/#%C2%BFEn_que_se_diferencia_3iPunt_del_resto\" >\u00bfEn qu\u00e9 se diferencia  3iPunt del resto?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p><\/p>\n\n\n\n<p>En 3ipunt hemos trabajado duro para obtener el reconocimiento por parte de Moodle y destacar como empresa experta en e-Learning con la capacidad de ofrecer el servicio y productos de Moodle. <strong>Lo hemos conseguido, somos el primer Premium Partner de Moodle en espa\u00f1ol.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_ser_Premium_Partner_de_Moodle\"><\/span><strong>\u00bfQu\u00e9 es ser Premium Partner de Moodle?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"inherit-container-width wp-block-group is-layout-constrained wp-block-group-is-layout-constrained advgb-dyn-ac567526\">\n<p><span style=\"font-weight: 400;\">Recordando tiempo atr\u00e1s, en noviembre de 2020&#8230;<\/span><\/p>\n<p>\u00a0<\/p>\n<blockquote>\n<p><em><span style=\"font-weight: 400;\">\u00abEstamos contentos por anunciar que en 3ipunt hemos obtenido el sello <strong>Premium Certified Services Provider<\/strong><\/span><span style=\"font-weight: 400;\">\u00a0como <strong>socio certificado de Moodle<\/strong>, la plataforma de aprendizaje de c\u00f3digo abierto m\u00e1s utilizada del mundo.\u00bb<\/span><\/em><\/p>\n<\/blockquote>\n<p><!--more--><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s de un largo y exigente proceso de calificaci\u00f3n por parte de Moodle, fue un honor el recibir el sello <\/span><a href=\"https:\/\/moodle.com\/es\/partners\/3ipunt\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Premium Partner<\/span><\/a><span style=\"font-weight: 400;\"> el <\/span><b>primero y \u00fanico de Espa\u00f1a.<\/b><\/p>\n<p>\u00a0<\/p>\n<p>Este reconocimiento nos ha permitido alcanzar el m\u00e1ximo nivel entre su red de socios, con la posibilidad de <strong>ofrecer todos los productos y servicios de Moodle<\/strong>, incluyendo la oferta corporativa de <a href=\"https:\/\/tresipunt.com\/es\/moodle-elearning\/workplace\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Moodle Workplace<\/strong><\/a> y el alojamiento en la nube con altos est\u00e1ndares de cumplimiento <em>cloud,<\/em> en servidores AWS.<\/p>\n<p>\u00a0<\/p>\n<blockquote>\n<p><em><strong>3ipunt<\/strong>, primer <b>Premium Partner de Moodle en Espa\u00f1a. Premium Certified Services Provider<\/b><\/em><\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<p>Coincidiendo con la celebraci\u00f3n de la MoodleMoot Spain Online 2020 los d\u00edas 17 y 18 de noviembre, el evento sobre Moodle m\u00e1s importante para la comunidad hispanohablante del que 3ipunt es <strong>Patrocinador <em>Platinum<\/em><\/strong>, se anunci\u00f3 el nuevo nivel Premium Partner, pasando as\u00ed a formar parte del selecto grupo de dieciocho socios con la m\u00e1xima distinci\u00f3n a nivel mundial.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Jose Marcos Lopez-Rios, Channel Manager para EMEA, Moodle, remarca la excelencia de 3ipunt afirmando que \u201c<em>como testimonio de su experiencia y profesionalismo por parte de todos los miembros del equipo en los proyectos en los que hemos colaborado con ellos, estamos orgullosos de nombrar a 3ipunt como nuestro primer socio Moodle Premium certificado en espa\u00f1ol\u201d.<\/em><\/p>\n<p>\u00a0<\/p>\n<p>Desde entonces y como ya lo hac\u00edamos antes, no hemos dejado de trabajar en el <strong>la implementaci\u00f3n y desarrollo a medida de la plataforma de formaci\u00f3n online<\/strong> para empresas, instituciones, etc, d\u00e1ndonos la oportunidad de seguir creciendo en el sector de la educaci\u00f3n a distancia de forma mucho m\u00e1s precisa y compleja para ofrecer el m\u00e1ximo beneficio de Moodle a nuestros clientes.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>A d\u00eda de hoy, 3ipunt destaca en el sector de la educaci\u00f3n online como <strong>expertos en e-learning<\/strong> ya que a parte de crear y gestionar plataformas Moodle,\u00a0 desarrollamos a medida cualquier integraci\u00f3n de Moodle en la herramienta que tiene cada cliente.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full advgb-dyn-bc3ee590\"><img decoding=\"async\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2021\/12\/MoodlePartnerAwards21_Badge_Major-Open-Source-Contributor.png\" alt=\"Badge Major Open Source Contributor 2021\" class=\"wp-image-6272\"\/><\/figure>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFEn_que_se_diferencia_3iPunt_del_resto\"><\/span><strong>\u00bfEn qu\u00e9 se diferencia  3iPunt del resto?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><\/p>\n\n\n<p>Despu\u00e9s de m\u00e1s de <strong>dieciocho a\u00f1os<\/strong> de experiencia contrastada como desarrolladores, hemos consolidado nuestra posici\u00f3n como empresa de capacidad integradora, apostando fuerte por la filosof\u00eda basada en las tecnolog\u00edas <strong><em>open source<\/em><\/strong> y la <strong>artesan\u00eda inform\u00e1tica<\/strong>.<\/p>\n<p>\u00a0<\/p>\n<p>Con un <strong>trato muy cercano<\/strong>, y <strong>sistemas sostenibles<\/strong> y <strong>escalables<\/strong> en contraposici\u00f3n a las grandes consultoras, tenemos clientes tanto estatales como internacionales en sectores tan dispares como universidades, editoriales, en los sectores farmac\u00e9utico y hospitalario, y ONG&#8217;s.<\/p>\n<p>\u00a0<\/p>\n<p>Un camino largo desde que en 2004 di\u00e9ramos nuestros primeros pasos en el mundo del desarrollo de p\u00e1ginas web, gestores de contenidos (CMS), eCommerce y desarrollos y programaci\u00f3n a medida.<\/p>\n<p>\u00a0<\/p>\n<p>En 3ipunt contamos con una extensa experiencia en e-Learning para ayudarte a exprimir el magn\u00edfico potencial de la mayor plataforma LMS Moodle.<\/p>\n<p>\u00a0<\/p>\n<p>Para m\u00e1s informaci\u00f3n no dudes en visitar nuestra <a href=\"https:\/\/tresipunt.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">p\u00e1gina web<\/a> o enviarnos un correo a <a href=\"mailto:contacte@tresipunt.com\" target=\"_blank\" rel=\"noopener noreferrer\">contacte@tresipunt.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de un largo y exigente proceso de calificaci\u00f3n por parte de Moodle, es un honor poder anunciar que hemos recibido el sello Premium Partner el primero y \u00fanico de Espa\u00f1a.<\/p>\n","protected":false},"author":1,"featured_media":14554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[12,18],"tags":[22,23,24],"class_list":["post-13172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moodle","category-workplace","tag-desarrollo-moodle","tag-expertos-e-learning","tag-premium-partner-moodle"],"acf":[],"author_meta":{"display_name":"admin_tresipunt","author_link":"https:\/\/tresipunt.com\/es\/author\/admin_tresipunt\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2022\/08\/premium_partner_3-300x169.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/moodle\/\" class=\"advgb-post-tax-term\">Moodle<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">Workplace<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Moodle<\/span>","<span class=\"advgb-post-tax-term\">Workplace<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">desarrollo moodle<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">expertos e-learning<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">premium partner moodle<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">desarrollo moodle<\/span>","<span class=\"advgb-post-tax-term\">expertos e-learning<\/span>","<span class=\"advgb-post-tax-term\">premium partner moodle<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 4 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 3 de agosto de 2022","modified":"Actualizado el 27 de enero de 2024"},"absolute_dates_time":{"created":"Publicado el 3 de agosto de 2022 00:00","modified":"Actualizado el 27 de enero de 2024 19:53"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=13172"}],"version-history":[{"count":5,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13172\/revisions"}],"predecessor-version":[{"id":24911,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13172\/revisions\/24911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/14554"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=13172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=13172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=13172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}