{"id":13224,"date":"2022-09-15T00:00:00","date_gmt":"2022-09-14T22:00:00","guid":{"rendered":"https:\/\/tresipunt.com\/moodlemoot-global-2022-tecnologia-y-educacion\/"},"modified":"2024-11-13T12:26:18","modified_gmt":"2024-11-13T11:26:18","slug":"moodlemoot-global-2022-tecnologia-y-educacion","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/","title":{"rendered":"MoodleMoot Global 2022: tecnolog\u00eda y educaci\u00f3n"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/#Moodle_y_sus_posibilidades_en_la_formacion_elearning\" >Moodle y sus posibilidades en la formaci\u00f3n elearning<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/#%C2%BFPor_que_debo_ir_a_la_MoodleMoot_Global_2022\" >\u00bfPor qu\u00e9 debo ir a la MoodleMoot Global 2022?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/#Conferencias_y_presentaciones\" >Conferencias y presentaciones<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/#Nuestras_charlas_en_la_MoodleMoot_Global_de_Barcelona\" >Nuestras charlas en la MoodleMoot Global de Barcelona<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/tresipunt.com\/es\/moodlemoot-global-2022-tecnologia-y-educacion\/#%C2%BFDe_que_va_a_hablar_3ipunt_en_sus_charlas_MoodleMoot\" >\u00bfDe qu\u00e9 va a hablar 3ipunt en sus charlas MoodleMoot?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Vuelve la MoodleMoot Global a Barcelona, el encuentro anual en el que abordamos aspectos relacionados con la tecnolog\u00eda y la educaci\u00f3n. Aunque surge vinculado a la <a href=\"https:\/\/tresipunt.com\/es\/moodle\/\" target=\"_blank\" rel=\"noreferrer noopener\">plataforma Moodle<\/a>, y este sigue siendo uno de sus ejes centrales, tambi\u00e9n se trabajan otros muchos temas relacionados con el uso de la tecnolog\u00eda en la educaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Moodle_y_sus_posibilidades_en_la_formacion_elearning\"><\/span><strong>Moodle y sus posibilidades en la formaci\u00f3n elearning<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Moodle&nbsp;se&nbsp;trata de una herramienta extremadamente vers\u00e1til con muchas posibilidades de conexi\u00f3n integradas por&nbsp;defecto, ya que&nbsp;es el eje perfecto para integrar, mediante colaboraciones \u00fatiles, el software de c\u00f3digo abierto, orientado a la educaci\u00f3n p\u00fablica y de calidad, que ya existe en el mercado.<\/p>\n\n\n\n<p>El camino ya se ha iniciado con Big Blue Button y H5P, por ejemplo, y podr\u00eda continuar con el <strong>software de almacenamiento en la nube<\/strong>, los sistemas de informaci\u00f3n estudiantil, los sistemas de gesti\u00f3n escolar, el software de edici\u00f3n de documentos, etc.<\/p>\n\n\n\n<p>Vamos avanzando hacia un escenario en el que las escuelas no tengan que depender de la adquisici\u00f3n de licencias y puedan ser libres de crear sus propias formaciones online, los estudiantes puedan crecer con una mentalidad diferente y aprendiendo que se pueden crear alternativas a los grandes monopolios tecnol\u00f3gicos.<\/p>\n\n\n\n<p>De todo esto se va a hablar en la MoodelMoot Global, los pr\u00f3ximos d\u00edas 27, 28 y 29 de septiembre.<\/p>\n\n\n\n<p>Con la MoodleMoot Global de este a\u00f1o, se est\u00e1 creando una oportunidad \u00fanica para que al menos 600 Moodlers de todo el mundo se re\u00fanan para centrarse en nuestro tema del futuro de la educaci\u00f3n. Y 3ipunt forma parte del evento como <strong>Platinum Sponsor<\/strong>.&nbsp;<\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_debo_ir_a_la_MoodleMoot_Global_2022\"><\/span><strong>\u00bfPor qu\u00e9 debo ir a la MoodleMoot Global 2022?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El programa de la&nbsp;MoodleMoot&nbsp;Global de este a\u00f1o incluye m\u00e1s de 120 presentaciones, que cubren las tres transmisiones de conferencias: educadores, administradores y desarrolladores, distribuidas en sesiones tem\u00e1ticas.<\/p>\n\n\n\n<p>Con presentadores de 32 pa\u00edses diferentes, las sesiones combinan diferentes charlas, talleres y presentaciones de carteles de la comunidad de Moodle, Moodle Partners, Moodle&nbsp;HQ&nbsp;y patrocinadores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conferencias_y_presentaciones\"><\/span><strong>Conferencias y presentaciones<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Este a\u00f1o se incluyen presentaciones principales que cubren los diferentes flujos de conferencias, incluidas presentaciones de Martin Dougiamas, fundador y director ejecutivo de Moodle, y Andreia Inamorato, experto en educaci\u00f3n digital, tecnolog\u00edas educativas y educaci\u00f3n abierta y Oficial cient\u00edfico de la Comisi\u00f3n Europea, Centro Com\u00fan de Investigaci\u00f3n (JRC).<\/p>\n\n\n\n<p>La MoodleMoot Global tambi\u00e9n contar\u00e1 con sesiones comunitarias de la comunidad de Moodle, Moodle Partners y patrocinadores, talleres y sesiones pr\u00e1cticas, eventos sociales y de redes (\u00a1incluida la MoodleMoot Global Party!) \u00a1Y mucho m\u00e1s!<\/p>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Nuestras_charlas_en_la_MoodleMoot_Global_de_Barcelona\"><\/span><strong>Nuestras charlas en la MoodleMoot Global de Barcelona<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><a href=\"https:\/\/tresipunt.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">3ipunt<\/a>, como <strong>patrocinadores Platinum<\/strong> en la MoodleMoot Global de Barcelona, va a realizar varias charlas en las que hablaremos de varios puntos.<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large advgb-dyn-6dd99097\"><img decoding=\"async\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2022\/09\/MoodleMoot_tuit-1024x576.png\" alt=\"Nuestras charlas\" class=\"wp-image-11662\"\/><\/figure>\n\n\n\n<div style=\"height:58px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFDe_que_va_a_hablar_3ipunt_en_sus_charlas_MoodleMoot\"><\/span><strong>\u00bfDe qu\u00e9 va a hablar 3ipunt en sus charlas MoodleMoot?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Nuestros <a href=\"https:\/\/tresipunt.com\/es\/conoce-al-equipo\/\" target=\"_blank\" rel=\"noreferrer noopener\">expertos en Moodle<\/a> <a href=\"https:\/\/www.linkedin.com\/in\/pau-plana-i-salesas-b5513b1a\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pau Plana<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/antonibertran\/\" target=\"_blank\" rel=\"noreferrer noopener\">Antoni Bertran<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/eingles\/\" target=\"_blank\" rel=\"noreferrer noopener\">X\u00e8nia Ingl\u00e9s<\/a> y <a href=\"https:\/\/www.linkedin.com\/in\/meritxell-reves-a3990417\/\" target=\"_blank\" rel=\"noreferrer noopener\">Meritxell Rev\u00e9s<\/a> dar\u00e1n charlas sobre la ense\u00f1anza, el desarrollo y la gesti\u00f3n de Moodle.&nbsp;<\/p>\n\n\n\n<p>Se hablar\u00e1 de temas como el proyecto TandemMOOC que permite realizar tandems online con hablantes nativos y de c\u00f3mo nuestros desarrolladores de Moodle lo han integrado con WordPress.&nbsp;<\/p>\n\n\n\n<p>Creemos que la educaci\u00f3n digital es relevante para nuestro futuro como empresa y como sociedad, por ello os vamos a contar c\u00f3mo avanzar a una educaci\u00f3n m\u00e1s justa con el proyecto DD, un ecosistema de aprendizaje elearning de c\u00f3digo abierto.&nbsp;<\/p>\n\n\n\n<p>Meritxell Rev\u00e9s desarrollar\u00e1 una charla sobre Moodle Workplace y c\u00f3mo sacarle partido a trav\u00e9s de la asignaci\u00f3n de planes de aprendizaje y realizando matriculaciones de forma automatizada.<\/p>\n\n\n\n<p>Consideramos importante explicar c\u00f3mo gestionar tus contenidos en Moodle, para luego, distribuirlos a la tecnolog\u00eda que necesites (Vue, Angular, React y Node, entre otras). <\/p>\n\n\n\n<p>Daremos otra charla en la que se repasar\u00e1n los est\u00e1ndares de 1EdTech que permiten que nuestro Moodle se convierta en un ecosistema de aplicaciones.<\/p>\n\n\n\n<p>Finalizando con nuestras charlas, os contaremos qu\u00e9 debemos tener en cuenta para virtualizar nuestra formaci\u00f3n presencial considerando las caracter\u00edsticas de la formaci\u00f3n online.<\/p>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full advgb-dyn-d008eb5e\"><img decoding=\"async\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2022\/09\/pasted-image-0.png\" alt=\"logo 3ipunt\" class=\"wp-image-11666\"\/><\/figure>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>\u00a1Este a\u00f1o somos Platinum Sponsor de la MoodleMoot Global 2022!<\/strong><\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Tendremos un stand junto al escenario Moodle, en el que nos podr\u00e1s visitar, conocernos y participar en retos muy divertidos.&nbsp;<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>#letselearntogether #MootGlobal22<\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Vuelve la MoodleMoot Global a Barcelona, el encuentro anual en el que abordamos aspectos relacionados con la tecnolog\u00eda y la educaci\u00f3n. Aunque surge vinculado a la plataforma Moodle, y este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[13,12,18],"tags":[41,42,29],"class_list":["post-13224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-moodle","category-workplace","tag-cursos-moodle","tag-formacion-moodle","tag-mec"],"acf":[],"author_meta":{"display_name":"admin_tresipunt","author_link":"https:\/\/tresipunt.com\/es\/author\/admin_tresipunt\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2022\/10\/moodlemoot_2022_asifue_3-300x169.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/eventos\/\" class=\"advgb-post-tax-term\">Eventos<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/moodle\/\" class=\"advgb-post-tax-term\">Moodle<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">Workplace<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Eventos<\/span>","<span class=\"advgb-post-tax-term\">Moodle<\/span>","<span class=\"advgb-post-tax-term\">Workplace<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">cursos moodle<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">formaci\u00f3n Moodle<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">MEC<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">cursos moodle<\/span>","<span class=\"advgb-post-tax-term\">formaci\u00f3n Moodle<\/span>","<span class=\"advgb-post-tax-term\">MEC<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 4 a\u00f1os hace","modified":"Actualizado 1 a\u00f1o hace"},"absolute_dates":{"created":"Publicado el 15 de septiembre de 2022","modified":"Actualizado el 13 de noviembre de 2024"},"absolute_dates_time":{"created":"Publicado el 15 de septiembre de 2022 00:00","modified":"Actualizado el 13 de noviembre de 2024 12:26"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=13224"}],"version-history":[{"count":5,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13224\/revisions"}],"predecessor-version":[{"id":33607,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/13224\/revisions\/33607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/14048"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=13224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=13224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=13224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}