{"id":21650,"date":"2023-09-07T12:04:30","date_gmt":"2023-09-07T10:04:30","guid":{"rendered":"https:\/\/tresipunt.com\/?p=21650"},"modified":"2023-10-26T11:24:27","modified_gmt":"2023-10-26T09:24:27","slug":"impartir-formacion-online","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/","title":{"rendered":"Todo lo que necesitas para impartir formaci\u00f3n online"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#%C2%BFComo_impartir_un_curso_en_linea\" >\u00bfC\u00f3mo impartir un curso en l\u00ednea?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Preparacion_de_las_clases\" >Preparaci\u00f3n de las clases<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Herramientas_digitales_de_formacion\" >Herramientas digitales de formaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Planifica_el_calendario_de_sesiones\" >Planifica el calendario de sesiones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Tamano_y_horarios_de_las_clases_virtuales\" >Tama\u00f1o y horarios de las clases virtuales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Interactividad_en_tus_clases_online\" >Interactividad en tus clases online<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Confianza_con_los_alumnos\" >Confianza con los alumnos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/tresipunt.com\/es\/impartir-formacion-online\/#Impartir_formacion_online_con_Moodle\" >Impartir formaci\u00f3n online con Moodle<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Las <strong>clases virtuales<\/strong> en los \u00faltimos a\u00f1os han experimentado un crecimiento exponencial siendo cada vez m\u00e1s demandadas.<\/p>\n\n\n\n<p>Los centros donde se imparte formaci\u00f3n tradicional <strong>complementan la educaci\u00f3n con plataformas educativas<\/strong> y recursos tecnol\u00f3gicos, ofreciendo al alumno un extra, fortaleciendo as\u00ed el estudio con actividades pr\u00e1cticas y l\u00fadicas, obteniendo una experiencia formativa m\u00e1s completa.<\/p>\n\n\n\n<p>El pensamiento humano tambi\u00e9n ha experimentado un cambio: ya no solo los j\u00f3venes buscan formaci\u00f3n, ahora buscan formaci\u00f3n las personas de cualquier edad.<\/p>\n\n\n\n<p>Sin duda es una <strong>evoluci\u00f3n a nivel sociedad y a nivel empresarial<\/strong>. Cada vez somos m\u00e1s cualificados en nuestros puestos de trabajo y fuera de ellos.<\/p>\n\n\n\n<p>La tecnolog\u00eda ha jugado un papel muy importante en este sentido. Los centros educativos han apostado por <a href=\"https:\/\/tresipunt.com\/es\/invertir-en-elearning\/\">invertir en sistemas de gesti\u00f3n del aprendizaje (LMS)<\/a> y poder ofrecer cursos online de calidad para distintos p\u00fablicos.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_impartir_un_curso_en_linea\"><\/span>\u00bfC\u00f3mo impartir un curso en l\u00ednea?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Si est\u00e1s pensando en impartir formaci\u00f3n online, te vamos a dar las claves para que lo puedas hacer con total \u00e9xito.<\/p>\n\n\n\n<p>Para impartir clases online se debe hacer una <strong>planificaci\u00f3n previa<\/strong> y pensar c\u00f3mo se van a afrontar distintas tareas.<\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Preparacion_de_las_clases\"><\/span>Preparaci\u00f3n de las clases<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Haz c\u00f3modo el ambiente, sin ning\u00fan tipo de distracci\u00f3n. Busca un espacio con una <strong>buena iluminaci\u00f3n<\/strong> y ten en orden todo lo necesario para que en tus clases en directo tengas todo a mano.<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized advgb-dyn-ba8bb9e5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/iStock-1221852205-1024x683.jpg\" alt=\"\" class=\"wp-image-21652\" style=\"width:496px;height:331px\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/iStock-1221852205-1024x683.jpg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/iStock-1221852205-300x200.jpg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/iStock-1221852205-768x512.jpg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/iStock-1221852205.jpg 1253w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Herramientas_digitales_de_formacion\"><\/span>Herramientas digitales de formaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Pensar en cu\u00e1l es la<a href=\"https:\/\/tresipunt.com\/moodle-elearning\/\"> mejor plataforma de formaci\u00f3n online<\/a> que se adapte a tus necesidades es uno de los factores m\u00e1s importantes. Esta debe ser <strong>\u00e1gil e intuitiva<\/strong> tanto para el que imparte formaci\u00f3n como para el estudiante. De esta manera podemos evitar cualquier problema que surja a nivel tecnol\u00f3gico.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Planifica_el_calendario_de_sesiones\"><\/span>Planifica el calendario de sesiones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Procura un espacio en tu plataforma elearning donde los alumnos puedan tener a mano el horario y d\u00eda de las sesiones para que ellos puedan organizarse.&nbsp;<\/p>\n\n\n\n<p>Las sesiones que no sean en tiempo real (as\u00edncronas), ponlas a disposici\u00f3n de los alumnos para que puedan visualizarlas sin limitaciones de horarios.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tamano_y_horarios_de_las_clases_virtuales\"><\/span>Tama\u00f1o y horarios de las clases virtuales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A nivel pr\u00e1ctico, las plataformas digitales no suelen tener <strong>l\u00edmite de alumnos<\/strong> por clase ni <strong>l\u00edmite de tiempo<\/strong> de duraci\u00f3n de las sesiones, pero es aconsejable conocer este aspecto. Es importante tener en cuenta tambi\u00e9n si se pueden invitar a alumnos que no est\u00e9n en esa convocatoria concreta o no pertenezcan a esa materia.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Interactividad_en_tus_clases_online\"><\/span>Interactividad en tus clases online<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En los cursos que planifiques puedes incorporar actividades l\u00fadicas con ejercicios interactivos, cuestionarios, etc.&nbsp;<br>Los<strong> videos interactivos<\/strong> tienen muy buenos resultados, dado que hoy en d\u00eda la visualizaci\u00f3n de v\u00eddeos es algo que ya hemos incorporado en nuestra vida cotidiana.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Confianza_con_los_alumnos\"><\/span>Confianza con los alumnos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Las clases online pueden hacerse con <strong>webcam <\/strong>o sin ella. Igualmente, se pueden hacer grabaciones para que el alumno pueda acceder a esa clase si no ha podido asistir en tiempo real.<\/p>\n\n\n\n<p>En el caso de utilizar c\u00e1mara, es de vital importancia<strong> generar confianza al alumno<\/strong>, hacerle sentir c\u00f3modo, sonriendo y permitiendo la interacci\u00f3n entre ellos y con el profesor mediante di\u00e1logos bidireccionales.<\/p>\n\n\n\n<p>Al finalizar cada clase, se puede hacer una<strong> ronda de preguntas<\/strong>. En las plataformas virtuales de aprendizaje existe la funci\u00f3n <strong>\u201clevantar la mano\u201d<\/strong> igual que en la educaci\u00f3n tradicional. De esta manera se establece un orden con el que el profesor le otorga el turno al estudiante para que formule su pregunta.<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impartir_formacion_online_con_Moodle\"><\/span>Impartir formaci\u00f3n online con Moodle<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Nuestra <a href=\"https:\/\/tresipunt.com\/es\/\">experiencia en elearning<\/a> nos dice que Moodle es una alternativa perfecta como plataforma educativa online. Alcanza m\u00e1s de 200 millones de usuarios a nivel mundial, es una plataforma virtual multiling\u00fce, en constante actualizaci\u00f3n, intuitiva, robusta y flexible.<\/p>\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized advgb-dyn-29f7f861\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"646\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/goodle_banner-1024x646-1.png\" alt=\"\" class=\"wp-image-21656\" style=\"width:649px;height:410px\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/goodle_banner-1024x646-1.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/goodle_banner-1024x646-1-300x189.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/goodle_banner-1024x646-1-768x485.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si est\u00e1s en tus comienzos con la formaci\u00f3n online, en <strong>3ipunt <\/strong>hemos desarrollado <strong>Goodle, <\/strong>un LMS Saas basado en <a href=\"https:\/\/tresipunt.com\/es\/goodle\/\"><strong>Moodle para peque\u00f1as empresas<\/strong><\/a>, academias, etc. que buscan una plataforma para impartir formaci\u00f3n <strong>econ\u00f3mica y sin complicaciones<\/strong>, con todo incluido para que solo tengas que formar a tus alumnos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfVas a impartir formaci\u00f3n online? Te contamos todo lo que necesitas para que tus cursos online sean todo un \u00e9xito.<\/p>\n","protected":false},"author":1,"featured_media":22812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[159],"tags":[],"class_list":["post-21650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning"],"acf":[],"author_meta":{"display_name":"admin_tresipunt","author_link":"https:\/\/tresipunt.com\/es\/author\/admin_tresipunt\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/09\/ESP-300x169.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/e-learning\/\" class=\"advgb-post-tax-term\">eLearning<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">eLearning<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 a\u00f1os hace","modified":"Actualizado 3 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 7 de septiembre de 2023","modified":"Actualizado el 26 de octubre de 2023"},"absolute_dates_time":{"created":"Publicado el 7 de septiembre de 2023 12:04","modified":"Actualizado el 26 de octubre de 2023 11:24"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/21650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=21650"}],"version-history":[{"count":5,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/21650\/revisions"}],"predecessor-version":[{"id":22811,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/21650\/revisions\/22811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/22812"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=21650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=21650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=21650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}