{"id":23675,"date":"2023-11-23T09:16:48","date_gmt":"2023-11-23T08:16:48","guid":{"rendered":"https:\/\/tresipunt.com\/?p=23675"},"modified":"2026-04-24T12:45:05","modified_gmt":"2026-04-24T10:45:05","slug":"aprendizaje-flexible-escalable-moodle-workplace","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/aprendizaje-flexible-escalable-moodle-workplace\/","title":{"rendered":"Aprendizaje flexible y escalable con Moodle Workplace"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/aprendizaje-flexible-escalable-moodle-workplace\/#Necesidades_formativas_de_EIT_Climate-KIC\" >Necesidades formativas de EIT Climate-KIC<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/aprendizaje-flexible-escalable-moodle-workplace\/#Moodle_Workplace_para_la_educacion_climatica\" >Moodle Workplace para la educaci\u00f3n clim\u00e1tica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/aprendizaje-flexible-escalable-moodle-workplace\/#Moodle_en_el_lugar_de_trabajo\" >Moodle en el lugar de trabajo<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Un nuevo \u00e9xito, esta vez de la mano de EIT Climate-KIC y agradeciendo la confianza que han depositado en <a href=\"https:\/\/tresipunt.com\/es\/\">3iPunt<\/a> para desarrollar un entorno de aprendizaje flexible.&nbsp;<\/p>\n\n\n\n<p>La <a href=\"https:\/\/www.climate-kic.org\/\" target=\"_blank\" rel=\"noopener\">EIT Climate-KIC<\/a>, en su apoyo a la <strong>educaci\u00f3n clim\u00e1tica<\/strong>, ten\u00eda como desaf\u00edo <a href=\"https:\/\/tresipunt.com\/es\/elearning-para-empresas\/\">facilitar el aprendizaje interno<\/a> y atender a profesionales que desean desarrollar habilidades relacionadas con el cambio clim\u00e1tico.&nbsp;Su sistema educativo necesitaba renovarse y como <a href=\"https:\/\/tresipunt.com\/es\/3ipunt-primer-premium-partner-de-moodle-de-espana\/\"><strong>socios Premium de Moodle<\/strong><\/a>, pudimos colaborar en su proyecto para ofrecer una soluci\u00f3n m\u00e1s innovadora y eficaz.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-1024x256.png\" alt=\"\" class=\"wp-image-23676\" style=\"aspect-ratio:4;width:783px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-1024x256.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-300x75.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-768x192.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1.png 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Necesidades_formativas_de_EIT_Climate-KIC\"><\/span>Necesidades formativas de EIT Climate-KIC<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Su LMS se ha utilizado principalmente por profesores y socios que empoderan a los estudiantes de secundaria para adentrarse y resolver la crisis clim\u00e1tica. La agencia de la Uni\u00f3n Europea en los \u00faltimos tiempos deseaba incorporar m\u00e1s cursos al LMS para facilitar el aprendizaje interno y dar cabida a profesionales que quieran aprender sobre el cambio clim\u00e1tico y adoptar competencias relacionadas con el cambio clim\u00e1tico.<\/p>\n\n\n\n<p>En resumen, EIT Climate-KIC ten\u00eda la necesidad de escalar el desarrollo de sus cursos y que estos fueran m\u00e1s <strong>flexibles y sencillos<\/strong> para cumplir su objetivo: el <strong>cambio de mentalidad<\/strong> y el <strong>fomento del conocimiento clim\u00e1tico<\/strong>, proponiendo una soluci\u00f3n educativa para ello.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Moodle_Workplace_para_la_educacion_climatica\"><\/span>Moodle Workplace para la educaci\u00f3n clim\u00e1tica<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Evaluados todos los requisitos concretos y el sistema actual del que dispon\u00edan, se eligi\u00f3 <strong>incorporar Moodle Workplace a su formaci\u00f3n interna<\/strong> para ofrecer una soluci\u00f3n integral.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"508\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25-1024x508.png\" alt=\"Inicio sessi\u00f3n climate-kic\" class=\"wp-image-23679\" style=\"aspect-ratio:2.015748031496063;width:868px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25-1024x508.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25-300x149.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25-768x381.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25-1536x762.png 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/23-08-2023_09-39-25.png 1896w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2-1024x505.png\" alt=\"Inicio sessi\u00f3n- climate kic tenant 2\" class=\"wp-image-23682\" style=\"aspect-ratio:2.0296610169491527;width:869px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2-1024x505.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2-300x148.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2-768x378.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2-1536x757.png 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/tenant-2.png 1916w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Este <a href=\"https:\/\/tresipunt.com\/es\/moodle-elearning\/workplace\/\">Moodle, destinado a empresas<\/a>, permite ofrecer espacios de trabajo personalizados a los usuarios, cada uno con su estructura, apariencia y entidades de aprendizaje distintas.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"348\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-1.png\" alt=\"Inicio sessi\u00f3n RELAI - tenant3\n\" class=\"wp-image-23686\" style=\"aspect-ratio:1.9683908045977012;width:819px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-1.png 685w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/pasted-image-0-1-1-300x152.png 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure>\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Han podido integrar en sus ofertas educativas ciertos ajustes adaptados a las necesidades concretas de cada alumno.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"483\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-1024x483.png\" alt=\"Inicio curso climatekic\" class=\"wp-image-23689\" style=\"aspect-ratio:2.12008281573499;width:802px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-1024x483.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-300x142.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-768x362.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-1536x725.png 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard.png 1908w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"499\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2-1024x499.png\" alt=\"Inicio curso - tenant1\" class=\"wp-image-23692\" style=\"aspect-ratio:2.0521042084168335;width:806px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2-1024x499.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2-300x146.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2-768x374.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2-1536x749.png 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/Dashboard-2.png 1904w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Desde la integraci\u00f3n de Moodle Workplace como sistema de aprendizaje, EIT Climate-KIC no solo ha <strong>mejorado en su educaci\u00f3n clim\u00e1tica<\/strong>, sino que su <strong>productividad ha aumentado significativamente<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Las posibilidades de <strong>Moodle Workplace revolucionan la formaci\u00f3n en las empresas<\/strong> y sus capacidades de itinerarios a medida y personalizaci\u00f3n han hecho posible este caso de \u00e9xito.&nbsp;<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/climate_video-1.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Moodle_en_el_lugar_de_trabajo\"><\/span>Moodle en el lugar de trabajo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Con Moodle Workplace las organizaciones tienen la posibilidad de crear experiencias de aprendizaje completamente personalizadas para cumplir con los objetivos que requieran las empresas.&nbsp;<\/p>\n\n\n\n<p>El<strong> LMS de capacitaci\u00f3n corporativa<\/strong> ya est\u00e1 presente en muchos negocios donde se ofrecen todo tipo de capacitaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Incorporaci\u00f3n de nuevos empleados<\/strong>: este proceso es m\u00e1s simple si se ofrece una plataforma centralizada para que los nuevos empleados accedan a los recursos, trabajen a trav\u00e9s de cursos relacionados con su nuevo rol y completen evaluaciones para demostrar su aprendizaje y competencia.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aprendizaje medible<\/strong>: Los informes anal\u00edticos y personalizados desde Moodle Workplace nos permiten medir r\u00e1pidamente la participaci\u00f3n y evoluci\u00f3n del alumno, el progreso y m\u00e1s. Estos datos pueden permitir una toma de decisiones con respecto al alumno.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cumplimiento y certificaci\u00f3n<\/strong>: los empleados pueden ser notificados autom\u00e1ticamente cuando vencen las certificaciones. Los informes de cumplimiento tambi\u00e9n facilitan la generaci\u00f3n de informes sobre el estado de cada empleado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rutas de aprendizaje personalizadas<\/strong>: este LMS proporciona itinerarios personalizados de tal manera que cada alumno recibe la formaci\u00f3n espec\u00edfica.&nbsp;<\/li>\n\n\n\n<li><strong>Cat\u00e1logo de cursos de desarrollo profesional<\/strong>: retener el talento y formar profesionales es una manera de ofrecer un valor diferencial en la empresa. Con Moodle Workplace se pueden ofrecer cursos de desarrollo profesional donde ellos puedan elegir su pr\u00f3ximo reto.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo Moodle Workplace puede ayudar a las empresas a personalizar sus formaciones. Te contamos el caso de \u00e9xito EIT Climate-KIC y 3iPunt.<\/p>\n","protected":false},"author":1,"featured_media":46465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[187,18],"tags":[],"class_list":["post-23675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casos-de-exito","category-workplace"],"acf":[],"author_meta":{"display_name":"admin_tresipunt","author_link":"https:\/\/tresipunt.com\/es\/author\/admin_tresipunt\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2023\/11\/esp-300x169.webp","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/casos-de-exito\/\" class=\"advgb-post-tax-term\">Casos de \u00e9xito<\/a>","<a href=\"https:\/\/tresipunt.com\/es\/blog\/workplace\/\" class=\"advgb-post-tax-term\">Workplace<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Casos de \u00e9xito<\/span>","<span class=\"advgb-post-tax-term\">Workplace<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 3 semanas hace"},"absolute_dates":{"created":"Publicado el 23 de noviembre de 2023","modified":"Actualizado el 24 de abril de 2026"},"absolute_dates_time":{"created":"Publicado el 23 de noviembre de 2023 09:16","modified":"Actualizado el 24 de abril de 2026 12:45"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/23675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=23675"}],"version-history":[{"count":4,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/23675\/revisions"}],"predecessor-version":[{"id":46472,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/23675\/revisions\/46472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/46465"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=23675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=23675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=23675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}