{"id":27082,"date":"2024-04-11T10:39:07","date_gmt":"2024-04-11T08:39:07","guid":{"rendered":"https:\/\/tresipunt.com\/?p=27082"},"modified":"2024-04-15T08:38:55","modified_gmt":"2024-04-15T06:38:55","slug":"tresipunt-aniversario-20-anos","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/","title":{"rendered":"\u00a1Celebramos 20 a\u00f1os de eLearning y tecnolog\u00eda!"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Proyectos_de_estandarizacion_con_LTI\" >Proyectos de estandarizaci\u00f3n con LTI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Integracion_de_exeLearning_en_Moodle\" >Integraci\u00f3n de exeLearning en Moodle<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Plugin_para_organizar_votaciones\" >Plugin para organizar votaciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Elaboracion_de_un_portafolio_vinculado_a_las_competencias_educativas\" >Elaboraci\u00f3n de un portafolio vinculado a las competencias educativas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Lanzamiento_de_productos_propios\" >Lanzamiento de productos propios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/tresipunt.com\/es\/tresipunt-aniversario-20-anos\/#Ampliando_fronteras\" >Ampliando fronteras<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Hoy escribimos estas l\u00edneas para celebrar una fecha muy importante en nuestra empresa: <strong>\u00a120 a\u00f1os en el mundo de la tecnolog\u00eda y el eLearning!<\/strong><\/p>\n\n\n\n<p>Desde que <strong>iniciamos esta aventura hace m\u00e1s de 7.300 d\u00edas<\/strong>, hemos sido testigos de cambios significativos en la sociedad, la tecnolog\u00eda y en nosotros mismos. La moda ha evolucionado, los peinados han cambiado, han nacido mini-3ipunteros y en el \u00e1mbito deportivo, incluso hemos presenciado dos tripletes del Bar\u00e7a.&nbsp;<\/p>\n\n\n\n<p>Antoni, Ebra y Pau, empezaron 3ipunt en el <em>Viver de Barcelona Activa<\/em>, para unos a\u00f1os m\u00e1s tarde mudarse a un \u00e1tico en la c. Arag\u00f3 de Barcelona, y de casa en casa y tiro porque me toca acabaron traslad\u00e1ndose a la c. Val\u00e8ncia para que cupi\u00e9ramos todos. Y eso no fue todo, porque decidieron empezar una nueva aventura en Madrid.<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"757\" data-id=\"27083\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-1-1-1024x757.png\" alt=\"Primera oficina Barcelona\" class=\"wp-image-27083\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-1-1-1024x757.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-1-1-300x222.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-1-1-768x568.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-1-1.png 1232w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" data-id=\"27086\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-2.png\" alt=\"Segona oficina Barcelona\" class=\"wp-image-27086\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-2.png 800w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-2-300x200.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/pasted-image-0-2-768x512.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" data-id=\"27089\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042.jpg\" alt=\"3ra oficina Barcelona\" class=\"wp-image-27089\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042.jpg 1600w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042-300x169.jpg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042-1024x576.jpg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042-768x432.jpg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/1000050042-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"27087\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53-1024x768.jpeg\" alt=\"Oficina Madrid\" class=\"wp-image-27087\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53-1024x768.jpeg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53-300x225.jpeg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53-768x576.jpeg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53-1536x1152.jpeg 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-20-at-10.15.53.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Durante estas dos d\u00e9cadas, hemos tenido la oportunidad de hacer muchas cosas gracias a un <a href=\"https:\/\/tresipunt.com\/es\/conoce-al-equipo\/\" target=\"_blank\" rel=\"noreferrer noopener\">equipo excepcional de personas<\/a> con un esp\u00edritu cr\u00edtico, una insaciable curiosidad por aprender y un alt\u00edsimo nivel humano y t\u00e9cnico. Esto nos ha permitido abordar con \u00e9xito importantes proyectos y desaf\u00edos en \u00e1reas como <strong>e-learning<\/strong>, <strong>desarrollo web<\/strong>, <strong>sistemas<\/strong>, <strong>marketing <\/strong>y <strong>dise\u00f1o<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Proyectos_de_estandarizacion_con_LTI\"><\/span>Proyectos de estandarizaci\u00f3n con LTI<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Nos hemos destacado por nuestra contribuci\u00f3n a la estandarizaci\u00f3n con Learning Tools Interoperability (LTI). Hemos liderado proyectos que han facilitado la inclusi\u00f3n de la gesti\u00f3n de licencias de acceso en <a href=\"https:\/\/tresipunt.com\/es\/que-es-lti-y-beneficios\/\" target=\"_blank\" rel=\"noreferrer noopener\">contenidos educativos a trav\u00e9s de LTI<\/a>.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\"><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Integracion_de_exeLearning_en_Moodle\"><\/span><strong>Integraci\u00f3n de exeLearning en Moodle<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Hemos potenciado la funcionalidad de los LMS al integrar herramientas como <strong>exeLearning en Moodle<\/strong>. Esta integraci\u00f3n permite a los usuarios editar scorms directamente desde el LMS, simplificando el proceso de creaci\u00f3n y distribuci\u00f3n de contenidos educativos mediante Open Source.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Plugin_para_organizar_votaciones\"><\/span>Plugin para organizar votaciones<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En nuestra b\u00fasqueda continua de mejorar la experiencia de aprendizaje, hemos desarrollado el Kuet, <strong>un plugin para organizar votaciones<\/strong>, obtener respuestas r\u00e1pidas y sumergirte en la diversi\u00f3n y la competici\u00f3n, todo en un solo lugar. Este plugin da a los educadores una herramienta interactiva y din\u00e1mica para involucrar a los estudiantes.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Elaboracion_de_un_portafolio_vinculado_a_las_competencias_educativas\"><\/span><strong>Elaboraci\u00f3n de un portafolio vinculado a las competencias educativas<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Hemos creado soluciones personalizadas para centros de ense\u00f1anza, incluyendo un portafolio que se integra de manera efectiva con las <strong>competencias educativas<\/strong>.&nbsp;<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\"><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Lanzamiento_de_productos_propios\"><\/span><strong>Lanzamiento de productos propios<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Hemos desarrollado con mucho mimo nuestros propios productos buscando la mejora del aprendizaje educativo. Entre ellos se encuentran <a href=\"https:\/\/tresipunt.com\/es\/goodle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Goodle<\/a>, Fresk y Smatx.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\" start=\"5\"><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ampliando_fronteras\"><\/span>Ampliando fronteras <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Hemos ampliado nuestra presencia m\u00e1s all\u00e1 de Barcelona, estableciendo contacto con <strong>clientes en Latinoam\u00e9rica, EE.UU<\/strong> y otros pa\u00edses.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\"><\/ol>\n\n\n\n<p>Pero los socios ya hab\u00edan anticipado todos estos hitos. \u00bfC\u00f3mo? \u00bfQu\u00e9 no sabes c\u00f3mo lo hicieron? Te dejamos el v\u00eddeo para que lo descubras.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Celebrem 20 anys d&#039;eLearning i tecnologia\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/z_nXVATZDPU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En este momento de celebraci\u00f3n, queremos expresar nuestro m\u00e1s sincero <strong>agradecimiento a todos vosotros, nuestros clientes, colaboradores, seguidores y amigos<\/strong>. Sin vuestro apoyo y confianza, no habr\u00edamos llegado tan lejos. Estamos emocionados por lo que el futuro nos depara y esperamos seguir aprendiendo juntos durante muchos a\u00f1os m\u00e1s. Porque ya sab\u00e9is, Let\u2019s eLearn together!<\/p>\n\n\n\n<p>As\u00ed que, en nombre de todo el equipo de 3ipunt, queremos decir \u00a1gracias! Gracias por formar parte de nuestra familia, por confiar en nosotros y por ser parte de esta emocionante historia de 20 a\u00f1os.<\/p>\n\n\n\n<p>\u00a1Sigamos adelante juntos hacia un futuro lleno aprendizaje!<\/p>\n\n\n\n<p>\u00a1Gracias por ser parte de la familia 3ipunt!<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/Untitled-1024x682.jpg\" alt=\"Equipo 3ipunt\" class=\"wp-image-27094\" style=\"width:742px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/Untitled-1024x682.jpg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/Untitled-300x200.jpg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/Untitled-768x511.jpg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/Untitled.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Descubre c\u00f3mo hemos evolucionado en dos d\u00e9cadas de excelencia en eLearning. Nuestra experiencia de 20 a\u00f1os garantiza soluciones educativas innovadoras y adaptadas a tus necesidades.<\/p>\n","protected":false},"author":1,"featured_media":27212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[159],"tags":[],"class_list":["post-27082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning"],"acf":[],"author_meta":{"display_name":"admin_tresipunt","author_link":"https:\/\/tresipunt.com\/es\/author\/admin_tresipunt\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2024\/04\/esp-300x171.webp","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/e-learning\/\" class=\"advgb-post-tax-term\">eLearning<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">eLearning<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 11 de abril de 2024","modified":"Actualizado el 15 de abril de 2024"},"absolute_dates_time":{"created":"Publicado el 11 de abril de 2024 10:39","modified":"Actualizado el 15 de abril de 2024 08:38"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/27082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=27082"}],"version-history":[{"count":4,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/27082\/revisions"}],"predecessor-version":[{"id":27421,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/27082\/revisions\/27421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/27212"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=27082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=27082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=27082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}