{"id":37478,"date":"2025-05-22T12:02:28","date_gmt":"2025-05-22T10:02:28","guid":{"rendered":"https:\/\/tresipunt.com\/?p=37478"},"modified":"2025-07-30T09:58:12","modified_gmt":"2025-07-30T07:58:12","slug":"3ipunt-ahora-suma-480","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/3ipunt-ahora-suma-480\/","title":{"rendered":"\u00a13ipunt ahora suma 480!"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/3ipunt-ahora-suma-480\/#Seguimos_siendo_3ipunt_pero_con_mas_fuerza\" >Seguimos siendo 3ipunt pero con m\u00e1s fuerza<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/3ipunt-ahora-suma-480\/#El_mismo_equipo_los_mismos_valores_el_mismo_compromiso_y_las_mismas_ganas_de_hacerte_la_vida_mas_facil_con_nuestras_soluciones_a_medida_y_experiencia_en_el_mundo_del_eLearning_y_la_tecnologia\" >El mismo equipo, los mismos valores, el mismo compromiso y las mismas ganas de hacerte la vida m\u00e1s f\u00e1cil con nuestras soluciones a medida y experiencia en el mundo del eLearning y la tecnolog\u00eda.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/3ipunt-ahora-suma-480\/#%C2%BFQuien_es_Cuatroochenta\" >\u00bfQui\u00e9n es Cuatroochenta?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Nos hace much\u00edsima ilusi\u00f3n compartir contigo algo muy especial: <strong>3ipunt se une al grupo Cuatroochenta<\/strong>, un holding tecnol\u00f3gico internacional que apuesta fuerte por el talento, la innovaci\u00f3n y el eLearning.<\/p>\n\n\n\n<p>Despu\u00e9s de m\u00e1s de 20 a\u00f1os metidos de lleno en el mundo de la tecnolog\u00eda y del eLearning, damos un paso m\u00e1s para seguir creciendo.<strong> Cuatroochenta ha<\/strong> <strong>confiado en nuestro equipo, en<\/strong> <strong>nuestra experiencia<\/strong> <strong>y, sobre todo, en nuestra manera de hacer las cosas<\/strong>.<\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-1024x683.jpeg\" alt=\"\" class=\"wp-image-37468\" style=\"width:922px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-1024x683.jpeg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-300x200.jpeg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-768x512.jpeg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-1536x1024.jpeg 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Foto-3ipunt-suma-480-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Seguimos_siendo_3ipunt_pero_con_mas_fuerza\"><\/span>Seguimos siendo 3ipunt pero con m\u00e1s fuerza<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-advgb-infobox advgb-infobox-wrapper has-text-align-center advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1\"><div class=\"advgb-infobox-wrap\"><div class=\"advgb-infobox-icon-container\"><div class=\"advgb-infobox-icon-inner-container\"><i class=\"material-icons-outlined\">beenhere<\/i><\/div><\/div><div class=\"advgb-infobox-textcontent\"><h3 class=\"advgb-infobox-title\"><span class=\"ez-toc-section\" id=\"El_mismo_equipo_los_mismos_valores_el_mismo_compromiso_y_las_mismas_ganas_de_hacerte_la_vida_mas_facil_con_nuestras_soluciones_a_medida_y_experiencia_en_el_mundo_del_eLearning_y_la_tecnologia\"><\/span><strong>El mismo equipo, los mismos valores, el mismo compromiso y las mismas ganas de hacerte la vida m\u00e1s f\u00e1cil con nuestras soluciones a medida y experiencia en el mundo del eLearning<br>y la tecnolog\u00eda.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"advgb-infobox-text\"><\/p><\/div><\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Sumamos<\/strong> con el grupo tecnol\u00f3gico con presencia en 32 pa\u00edses, 300 personas expertas y una apuesta clara por el desarrollo de talento y tecnolog\u00eda.<\/p>\n\n\n\n<p><strong>Creciendo juntos<\/strong>. Esta uni\u00f3n nos permite seguir mejorando, crear nuevas herramientas y ofrecerte un servicio todav\u00eda m\u00e1s completo y personalizado.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQuien_es_Cuatroochenta\"><\/span><strong>\u00bfQui\u00e9n es Cuatroochenta?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong><a href=\"https:\/\/cuatroochenta.com\/\" target=\"_blank\" rel=\"noopener\">Cuatroochenta<\/a> es un<\/strong> <strong>holding tecnol\u00f3gico internacional<\/strong> dedicado a adquirir, desarrollar e invertir en compa\u00f1\u00edas innovadoras de tecnolog\u00eda, conocimiento especializado y ciberseguridad.<\/p>\n\n\n\n<p><strong>M\u00e1s de<\/strong> <strong>20 millones de personas<\/strong> usan a diario las soluciones de sus empresas. Con 12 oficinas en Espa\u00f1a y Am\u00e9rica Latina (Colombia, Costa Rica, M\u00e9xico, Panam\u00e1 y Rep\u00fablica Dominicana) en las que trabajan m\u00e1s de 300 personas, cotiza desde 2020 en <strong>BME Growth<\/strong>, el mercado burs\u00e1til espa\u00f1ol de empresas emergentes.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-1024x1024.jpg\" alt=\"\" class=\"wp-image-37471\" style=\"width:557px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-1024x1024.jpg 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-300x300.jpg 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-150x150.jpg 150w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-768x768.jpg 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-1536x1536.jpg 1536w, https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/Grafica-1-1-RRSS-acuerdo_480-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Esta<\/strong> <strong>integraci\u00f3n no cambia lo que m\u00e1s valoras de 3ipunt<\/strong>: cercan\u00eda, agilidad y trato directo. Solo que ahora vamos mejor acompa\u00f1ados.<\/p>\n\n\n\n<p>\u00bfTienes dudas o quieres saber m\u00e1s sobre lo que esto significa para ti?<\/p>\n\n\n\n<p>Escr\u00edbenos, estaremos encantados de cont\u00e1rtelo.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"mailto:contacte@tresipunt.com\">Contacta con nosotros<\/a><\/div>\n<\/div>\n\n\n\n<p>#letselearntogether #BeCuatroochenter<\/p>\n<style class=\"advgb-styles-renderer\">#advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1, .advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 {background-color: #f5f5f5;padding: 20px 20px 20px 20px;border: 0px solid #e8e8e8 ;border-radius: 0px;}#advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-icon-container, .advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-icon-container {background-color: #f5f5f5;padding: 0;margin: 0;border: 0px solid #e8e8e8 ;border-radius: 0px;}#advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-icon-container i, .advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-icon-container i {color: #333;font-size: 70px;display: block;}#advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-textcontent .advgb-infobox-title, .advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-textcontent .advgb-infobox-title {color: #333;padding: 0;margin: 5px 0 10px 0;white-space: pre-wrap;}#advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-textcontent .advgb-infobox-text, .advgb-infobox-40a52fef-ef2d-4742-80ae-43c4673dbaa1 .advgb-infobox-textcontent .advgb-infobox-text {color: #333;padding: 0;margin: 0;white-space: pre-wrap;}<\/style>","protected":false},"excerpt":{"rendered":"<p>3ipunt se une al grupo Cuatroochenta para seguir creciendo en el mundo del eLearning y la tecnolog\u00eda. Una nueva etapa con m\u00e1s fuerza, sin perder nuestra esencia ni la forma en la que nos gusta hacer las cosas.<\/p>\n","protected":false},"author":4,"featured_media":37481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[159],"tags":[],"class_list":["post-37478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning"],"acf":[],"author_meta":{"display_name":"Alba Illan","author_link":"https:\/\/tresipunt.com\/es\/author\/aillan\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2025\/05\/esp-2-300x169.webp","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/e-learning\/\" class=\"advgb-post-tax-term\">eLearning<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">eLearning<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 12 meses hace","modified":"Actualizado 10 meses hace"},"absolute_dates":{"created":"Publicado el 22 de mayo de 2025","modified":"Actualizado el 30 de julio de 2025"},"absolute_dates_time":{"created":"Publicado el 22 de mayo de 2025 12:02","modified":"Actualizado el 30 de julio de 2025 09:58"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/37478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=37478"}],"version-history":[{"count":4,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/37478\/revisions"}],"predecessor-version":[{"id":39420,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/37478\/revisions\/39420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/37481"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=37478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=37478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=37478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}