{"id":45839,"date":"2026-04-16T08:44:54","date_gmt":"2026-04-16T06:44:54","guid":{"rendered":"https:\/\/tresipunt.com\/?p=45839"},"modified":"2026-04-16T08:44:56","modified_gmt":"2026-04-16T06:44:56","slug":"por-que-plataforma-formacion-no-se-utiliza","status":"publish","type":"post","link":"https:\/\/tresipunt.com\/es\/por-que-plataforma-formacion-no-se-utiliza\/","title":{"rendered":"Por qu\u00e9 tu plataforma de formaci\u00f3n no se utiliza (y no es un problema de Moodle)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/tresipunt.com\/es\/por-que-plataforma-formacion-no-se-utiliza\/#La_plataforma_no_se_usa_porque_no_se_entiende\" >La plataforma no se usa porque no se entiende<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/tresipunt.com\/es\/por-que-plataforma-formacion-no-se-utiliza\/#Tener_cursos_no_es_lo_mismo_que_tener_formacion\" >Tener cursos no es lo mismo que tener formaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/tresipunt.com\/es\/por-que-plataforma-formacion-no-se-utiliza\/#La_experiencia_tambien_cuenta\" >La experiencia tambi\u00e9n cuenta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/tresipunt.com\/es\/por-que-plataforma-formacion-no-se-utiliza\/#Moodle_no_es_el_problema\" >Moodle no es el problema<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Muchas organizaciones se encuentran con el mismo problema: tienen una plataforma de formaci\u00f3n online (LMS), pero los usuarios no la utilizan. No es un fallo t\u00e9cnico, ni suele ser un problema de Moodle. Es algo m\u00e1s estructural.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_plataforma_no_se_usa_porque_no_se_entiende\"><\/span>La plataforma no se usa porque no se entiende<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Cuando alguien entra por primera vez (o vuelve despu\u00e9s de un tiempo), hay <strong>tres preguntas muy b\u00e1sicas<\/strong> que deber\u00edan responderse solas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 tengo que hacer aqu\u00ed?<\/li>\n\n\n\n<li>\u00bfPor d\u00f3nde empiezo?<\/li>\n\n\n\n<li>\u00bfEsto para qu\u00e9 me sirve?<\/li>\n<\/ul>\n\n\n\n<p>Si eso no est\u00e1 claro en los primeros segundos, algo se rompe.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tener_cursos_no_es_lo_mismo_que_tener_formacion\"><\/span>Tener cursos no es lo mismo que tener formaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Esto pasa mucho. Hay contenido. Hay cursos. A veces muchos. Pero no siempre hay una l\u00f3gica detr\u00e1s.<\/p>\n\n\n\n<p>Formaci\u00f3n obligatoria mezclada con opcional. Itinerarios poco definidos. Cat\u00e1logos que crecen sin demasiado criterio. Y al final, desde fuera, todo se ve igual.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/Group-1000001306-1536x900-1-1024x600.png\" alt=\"plataforma moodle\" class=\"wp-image-45840\" style=\"width:719px;height:auto\" srcset=\"https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/Group-1000001306-1536x900-1-1024x600.png 1024w, https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/Group-1000001306-1536x900-1-300x176.png 300w, https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/Group-1000001306-1536x900-1-768x450.png 768w, https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/Group-1000001306-1536x900-1.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_experiencia_tambien_cuenta\"><\/span>La experiencia tambi\u00e9n cuenta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Aqu\u00ed no hablamos de grandes redise\u00f1os ni de cosas complejas. Hablamos de <strong>detalles<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>C\u00f3mo se navega<\/li>\n\n\n\n<li>Qu\u00e9 se ve primero<\/li>\n\n\n\n<li>Qu\u00e9 se destaca<\/li>\n\n\n\n<li>Qu\u00e9 se esconde<\/li>\n<\/ul>\n\n\n\n<p>Peque\u00f1as decisiones que hacen que entrar en la plataforma sea algo natural\u2026 o algo que cuesta.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Moodle_no_es_el_problema\"><\/span>Moodle no es el problema<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A veces la reacci\u00f3n es clara: \u201cnecesitamos m\u00e1s funcionalidades\u201d. M\u00e1s automatizaciones, m\u00e1s cursos, m\u00e1s opciones. Pero muchas veces no va por ah\u00ed. De hecho, <strong>lo que mejor funciona suele ser lo contrario: ordenar, simplificar y dar sentido.<\/strong><\/p>\n\n\n\n<p>Moodle (y cualquier LMS bien trabajado) tiene de sobra para que una plataforma funcione. El cambio no suele venir de cambiar de herramienta, sino de <strong>cambiar c\u00f3mo se est\u00e1 utilizando.<\/strong><\/p>\n\n\n\n<p>De pasar de \u201ctenemos una plataforma\u201d a <strong>\u201ctenemos un entorno de aprendizaje que la gente usa\u201d.<\/strong> <\/p>\n\n\n\n<p>Te invitamos a probar el <strong>Form\u00f3metro<\/strong>, un test dise\u00f1ado para medir el nivel de madurez de la formaci\u00f3n en una organizaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/formometro.host3ip.eu\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00a1Quiero probar el Form\u00f3metro!<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En 3ipunt llevamos tiempo viendo este patr\u00f3n. Y casi nunca tiene que ver con la herramienta. Tiene que ver con c\u00f3mo se construye todo lo que hay alrededor. Porque al final, <strong>una plataforma no funciona mejor por todo lo que permite hacer\u2026sino por lo f\u00e1cil que resulta usarla.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre por qu\u00e9 tu plataforma de formaci\u00f3n no se utiliza y c\u00f3mo mejorar la experiencia en tu LMS sin cambiar de herramienta.<\/p>\n","protected":false},"author":4,"featured_media":45865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[159],"tags":[],"class_list":["post-45839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning"],"acf":[],"author_meta":{"display_name":"Alba Illan","author_link":"https:\/\/tresipunt.com\/es\/author\/aillan\/"},"featured_img":"https:\/\/tresipunt.com\/wp-content\/uploads\/2026\/04\/esp_3x-1-300x169.webp","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/tresipunt.com\/es\/blog\/e-learning\/\" class=\"advgb-post-tax-term\">eLearning<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">eLearning<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 4 semanas hace","modified":"Actualizado 4 semanas hace"},"absolute_dates":{"created":"Publicado el 16 de abril de 2026","modified":"Actualizado el 16 de abril de 2026"},"absolute_dates_time":{"created":"Publicado el 16 de abril de 2026 08:44","modified":"Actualizado el 16 de abril de 2026 08:44"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/45839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/comments?post=45839"}],"version-history":[{"count":4,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/45839\/revisions"}],"predecessor-version":[{"id":45871,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/posts\/45839\/revisions\/45871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media\/45865"}],"wp:attachment":[{"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/media?parent=45839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/categories?post=45839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tresipunt.com\/es\/wp-json\/wp\/v2\/tags?post=45839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}